{"id":125055,"date":"2022-02-05T07:22:28","date_gmt":"2022-02-05T06:22:28","guid":{"rendered":"https:\/\/www.italyfoodequipment.com\/?post_type=product&#038;p=125055"},"modified":"2024-07-26T17:18:35","modified_gmt":"2024-07-26T15:18:35","slug":"pasta-sheet-for-sirpasta-xp","status":"publish","type":"product","link":"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/","title":{"rendered":"Pasta sheet for Sirpasta XP"},"content":{"rendered":"<p>Dies in brass-bronze for <strong>pasta sheet width 173 mm<\/strong> for pasta machine Sirpasta XP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adjustable sheeter in brass-bronze.<br \/>\n<strong>Diameter Die:<\/strong>\u00a0\u00f8 75 mm<br \/>\n<strong>Width Sheet:<\/strong> 173 mm<\/p>\n","protected":false},"featured_media":125021,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1033,2851,2831,77],"product_tag":[2856,145,155,1787,3025],"class_list":["post-125055","product","type-product","status-publish","has-post-thumbnail","product_cat-dies","product_cat-dies-for-sirpasta-xp","product_cat-dies-sirman","product_cat-pasta-machines","product_tag-dies","product_tag-extruder","product_tag-pastamachine-en","product_tag-sirman-en","product_tag-sirpasta-xp-en","yith_product_brand-sirman-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pasta sheet for Sirpasta XP - Italy Food Equipment<\/title>\n<meta name=\"description\" content=\"Dies in brass-bronze for pasta sheet width 173 mm for pasta machine sir pasta xp\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pasta sheet for Sirpasta XP - Italy Food Equipment\" \/>\n<meta property=\"og:description\" content=\"Dies in brass-bronze for pasta sheet width 173 mm for pasta machine sir pasta xp\" \/>\n<meta property=\"og:url\" content=\"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/\" \/>\n<meta property=\"og:site_name\" content=\"Italy Food Equipment\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/italyfoodequipment1\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-26T15:18:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2022\/02\/Sirman-trafile-sfoglia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ItalyFoodEquipm\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/pasta-sheet-for-sirpasta-xp\\\/\",\"url\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/pasta-sheet-for-sirpasta-xp\\\/\",\"name\":\"Pasta sheet for Sirpasta XP - Italy Food Equipment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/pasta-sheet-for-sirpasta-xp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/pasta-sheet-for-sirpasta-xp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Sirman-trafile-sfoglia.jpg\",\"datePublished\":\"2022-02-05T06:22:28+00:00\",\"dateModified\":\"2024-07-26T15:18:35+00:00\",\"description\":\"Dies in brass-bronze for pasta sheet width 173 mm for pasta machine sir pasta xp\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/pasta-sheet-for-sirpasta-xp\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/pasta-sheet-for-sirpasta-xp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/pasta-sheet-for-sirpasta-xp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Sirman-trafile-sfoglia.jpg\",\"contentUrl\":\"https:\\\/\\\/italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Sirman-trafile-sfoglia.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/pasta-sheet-for-sirpasta-xp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"shop\",\"item\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pasta sheet for Sirpasta XP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/\",\"name\":\"Italy Food Equipment\",\"description\":\"Professional food equipment made in Italy. Fresh pasta machines, mixers, ovens and accessories for pizzerias and restaurants. Professional advice.\",\"publisher\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#organization\",\"name\":\"Italy Food Equipment\",\"url\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IFELOGO2021.png\",\"contentUrl\":\"https:\\\/\\\/www.italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IFELOGO2021.png\",\"width\":800,\"height\":239,\"caption\":\"Italy Food Equipment\"},\"image\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/italyfoodequipment1\\\/\",\"https:\\\/\\\/x.com\\\/ItalyFoodEquipm\",\"https:\\\/\\\/www.instagram.com\\\/italyfoodequipment\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/italyfoodequipment\\\/pins\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCei5o9afXohrZxw6DvkF88Q\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pasta sheet for Sirpasta XP - Italy Food Equipment","description":"Dies in brass-bronze for pasta sheet width 173 mm for pasta machine sir pasta xp","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/","og_locale":"en_US","og_type":"article","og_title":"Pasta sheet for Sirpasta XP - Italy Food Equipment","og_description":"Dies in brass-bronze for pasta sheet width 173 mm for pasta machine sir pasta xp","og_url":"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/","og_site_name":"Italy Food Equipment","article_publisher":"https:\/\/www.facebook.com\/italyfoodequipment1\/","article_modified_time":"2024-07-26T15:18:35+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2022\/02\/Sirman-trafile-sfoglia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ItalyFoodEquipm","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/","url":"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/","name":"Pasta sheet for Sirpasta XP - Italy Food Equipment","isPartOf":{"@id":"https:\/\/italyfoodequipment.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/#primaryimage"},"image":{"@id":"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/#primaryimage"},"thumbnailUrl":"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2022\/02\/Sirman-trafile-sfoglia.jpg","datePublished":"2022-02-05T06:22:28+00:00","dateModified":"2024-07-26T15:18:35+00:00","description":"Dies in brass-bronze for pasta sheet width 173 mm for pasta machine sir pasta xp","breadcrumb":{"@id":"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/#primaryimage","url":"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2022\/02\/Sirman-trafile-sfoglia.jpg","contentUrl":"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2022\/02\/Sirman-trafile-sfoglia.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/italyfoodequipment.com\/en\/product\/pasta-sheet-for-sirpasta-xp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/italyfoodequipment.com\/en\/"},{"@type":"ListItem","position":2,"name":"shop","item":"https:\/\/italyfoodequipment.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Pasta sheet for Sirpasta XP"}]},{"@type":"WebSite","@id":"https:\/\/italyfoodequipment.com\/en\/#website","url":"https:\/\/italyfoodequipment.com\/en\/","name":"Italy Food Equipment","description":"Professional food equipment made in Italy. Fresh pasta machines, mixers, ovens and accessories for pizzerias and restaurants. Professional advice.","publisher":{"@id":"https:\/\/italyfoodequipment.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/italyfoodequipment.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/italyfoodequipment.com\/en\/#organization","name":"Italy Food Equipment","url":"https:\/\/italyfoodequipment.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/italyfoodequipment.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.italyfoodequipment.com\/wp-content\/uploads\/2021\/04\/IFELOGO2021.png","contentUrl":"https:\/\/www.italyfoodequipment.com\/wp-content\/uploads\/2021\/04\/IFELOGO2021.png","width":800,"height":239,"caption":"Italy Food Equipment"},"image":{"@id":"https:\/\/italyfoodequipment.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/italyfoodequipment1\/","https:\/\/x.com\/ItalyFoodEquipm","https:\/\/www.instagram.com\/italyfoodequipment\/","https:\/\/www.pinterest.com\/italyfoodequipment\/pins\/","https:\/\/www.youtube.com\/channel\/UCei5o9afXohrZxw6DvkF88Q"]}]}},"_links":{"self":[{"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/product\/125055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/comments?post=125055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/media\/125021"}],"wp:attachment":[{"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/media?parent=125055"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/product_brand?post=125055"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/product_cat?post=125055"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/product_tag?post=125055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}