{"id":1258,"date":"2015-09-14T17:40:52","date_gmt":"2015-09-14T15:40:52","guid":{"rendered":""},"modified":"2024-07-26T16:49:05","modified_gmt":"2024-07-26T14:49:05","slug":"rolling-machine-with-double-pair-rollers-rm45ta","status":"publish","type":"product","link":"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/","title":{"rendered":"Rolling machine with double pair of parallel rollers RM45TA"},"content":{"rendered":"<h3>Rolling machine with double pair of parallel rollers RM45TA<\/h3>\n<p><strong>The rolling machines have a steel structure and were designed to roll out dough for pizzas, flat bread, pies, etc. with considerable time savings\u00a0<\/strong>and without the need\u00a0 for specialised personnel.<br \/>\nThis version has the upper roller unit parallel to the lower unit for the production of circular or rectangular bases. The controls are digital. The slightly floured ball is inserted manually between the rollers through the opening of the upper protection, and a base is automatically produced that, with a manual operation, can have a rectangular form, which is ideal for baking in a tin. If when exiting the upper rollers, the dough is rotated half a turn by the operator, a round dough is obtained.<\/p>\n<p>Therefore, this machine is very versatile and functional, also due to the standard electric pedal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Dough weight:<\/strong> 210 \u00f7 700 gr<br \/>\n<strong>Pizza diameter: <\/strong>30 \u00f7 43 cm<br \/>\n<strong>Dimensions: <\/strong>590x530x730 (mm)<br \/>\n<strong>Weight: <\/strong>38 kg <strong>Power supply:<\/strong> 230V\/1N\/50Hz<\/p>\n","protected":false},"featured_media":156645,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3503,107,3783,116],"product_tag":[65,377,3767,389],"class_list":["post-1258","product","type-product","status-publish","has-post-thumbnail","product_cat-dough","product_cat-pizza-en","product_cat-pizza-spreader-en","product_cat-rolling-machines","product_tag-pizza-en","product_tag-pizzagroup-en","product_tag-preventivo-en","product_tag-rollingmachine-en","yith_product_brand-pizzagroup-en","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rolling machine with double pair of parallel rollers RM45TA - Italy Food Equipment<\/title>\n<meta name=\"description\" content=\"Pizza - Rolling machine with double pair of parallel rollers RM45TA Pizza Group - Dough weight 210 \u00f7 700 gr. Pizza diameter 30 \u00f7 43 cm.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rolling machine with double pair of parallel rollers RM45TA - Italy Food Equipment\" \/>\n<meta property=\"og:description\" content=\"Pizza - Rolling machine with double pair of parallel rollers RM45TA Pizza Group - Dough weight 210 \u00f7 700 gr. Pizza diameter 30 \u00f7 43 cm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/\" \/>\n<meta property=\"og:site_name\" content=\"Italy Food Equipment\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/italyfoodequipment1\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-26T14:49:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2022\/08\/PizzaGroup-Dilaminatrice-RM42TA-RM45TA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ItalyFoodEquipm\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/rolling-machine-with-double-pair-rollers-rm45ta\\\/\",\"url\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/rolling-machine-with-double-pair-rollers-rm45ta\\\/\",\"name\":\"Rolling machine with double pair of parallel rollers RM45TA - Italy Food Equipment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/rolling-machine-with-double-pair-rollers-rm45ta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/rolling-machine-with-double-pair-rollers-rm45ta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/RM42-A-RM45-A_-dilaminatrice.jpg\",\"datePublished\":\"2015-09-14T15:40:52+00:00\",\"dateModified\":\"2024-07-26T14:49:05+00:00\",\"description\":\"Pizza - Rolling machine with double pair of parallel rollers RM45TA Pizza Group - Dough weight 210 \u00f7 700 gr. Pizza diameter 30 \u00f7 43 cm.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/rolling-machine-with-double-pair-rollers-rm45ta\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/rolling-machine-with-double-pair-rollers-rm45ta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/rolling-machine-with-double-pair-rollers-rm45ta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/RM42-A-RM45-A_-dilaminatrice.jpg\",\"contentUrl\":\"https:\\\/\\\/italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/RM42-A-RM45-A_-dilaminatrice.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/product\\\/rolling-machine-with-double-pair-rollers-rm45ta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"shop\",\"item\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rolling machine with double pair of parallel rollers RM45TA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/\",\"name\":\"Italy Food Equipment\",\"description\":\"Professional food equipment made in Italy. Fresh pasta machines, mixers, ovens and accessories for pizzerias and restaurants. Professional advice.\",\"publisher\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#organization\",\"name\":\"Italy Food Equipment\",\"url\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IFELOGO2021.png\",\"contentUrl\":\"https:\\\/\\\/www.italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IFELOGO2021.png\",\"width\":800,\"height\":239,\"caption\":\"Italy Food Equipment\"},\"image\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/italyfoodequipment1\\\/\",\"https:\\\/\\\/x.com\\\/ItalyFoodEquipm\",\"https:\\\/\\\/www.instagram.com\\\/italyfoodequipment\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/italyfoodequipment\\\/pins\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCei5o9afXohrZxw6DvkF88Q\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rolling machine with double pair of parallel rollers RM45TA - Italy Food Equipment","description":"Pizza - Rolling machine with double pair of parallel rollers RM45TA Pizza Group - Dough weight 210 \u00f7 700 gr. Pizza diameter 30 \u00f7 43 cm.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/","og_locale":"en_US","og_type":"article","og_title":"Rolling machine with double pair of parallel rollers RM45TA - Italy Food Equipment","og_description":"Pizza - Rolling machine with double pair of parallel rollers RM45TA Pizza Group - Dough weight 210 \u00f7 700 gr. Pizza diameter 30 \u00f7 43 cm.","og_url":"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/","og_site_name":"Italy Food Equipment","article_publisher":"https:\/\/www.facebook.com\/italyfoodequipment1\/","article_modified_time":"2024-07-26T14:49:05+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2022\/08\/PizzaGroup-Dilaminatrice-RM42TA-RM45TA.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ItalyFoodEquipm","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/","url":"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/","name":"Rolling machine with double pair of parallel rollers RM45TA - Italy Food Equipment","isPartOf":{"@id":"https:\/\/italyfoodequipment.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/#primaryimage"},"image":{"@id":"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/#primaryimage"},"thumbnailUrl":"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2015\/09\/RM42-A-RM45-A_-dilaminatrice.jpg","datePublished":"2015-09-14T15:40:52+00:00","dateModified":"2024-07-26T14:49:05+00:00","description":"Pizza - Rolling machine with double pair of parallel rollers RM45TA Pizza Group - Dough weight 210 \u00f7 700 gr. Pizza diameter 30 \u00f7 43 cm.","breadcrumb":{"@id":"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/#primaryimage","url":"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2015\/09\/RM42-A-RM45-A_-dilaminatrice.jpg","contentUrl":"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2015\/09\/RM42-A-RM45-A_-dilaminatrice.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/italyfoodequipment.com\/en\/product\/rolling-machine-with-double-pair-rollers-rm45ta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/italyfoodequipment.com\/en\/"},{"@type":"ListItem","position":2,"name":"shop","item":"https:\/\/italyfoodequipment.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Rolling machine with double pair of parallel rollers RM45TA"}]},{"@type":"WebSite","@id":"https:\/\/italyfoodequipment.com\/en\/#website","url":"https:\/\/italyfoodequipment.com\/en\/","name":"Italy Food Equipment","description":"Professional food equipment made in Italy. Fresh pasta machines, mixers, ovens and accessories for pizzerias and restaurants. Professional advice.","publisher":{"@id":"https:\/\/italyfoodequipment.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/italyfoodequipment.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/italyfoodequipment.com\/en\/#organization","name":"Italy Food Equipment","url":"https:\/\/italyfoodequipment.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/italyfoodequipment.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.italyfoodequipment.com\/wp-content\/uploads\/2021\/04\/IFELOGO2021.png","contentUrl":"https:\/\/www.italyfoodequipment.com\/wp-content\/uploads\/2021\/04\/IFELOGO2021.png","width":800,"height":239,"caption":"Italy Food Equipment"},"image":{"@id":"https:\/\/italyfoodequipment.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/italyfoodequipment1\/","https:\/\/x.com\/ItalyFoodEquipm","https:\/\/www.instagram.com\/italyfoodequipment\/","https:\/\/www.pinterest.com\/italyfoodequipment\/pins\/","https:\/\/www.youtube.com\/channel\/UCei5o9afXohrZxw6DvkF88Q"]}]}},"_links":{"self":[{"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/product\/1258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/comments?post=1258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/media\/156645"}],"wp:attachment":[{"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/media?parent=1258"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/product_brand?post=1258"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/product_cat?post=1258"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/italyfoodequipment.com\/en\/wp-json\/wp\/v2\/product_tag?post=1258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}