{"id":2717,"count":2,"description":"Chez Italy Food Equipment, nous proposons des machines professionnelles pour la production automatique de cr\u00eapes, id\u00e9ales pour les \u00e9v\u00e9nements, les cantines, les \u00e9coles et les ateliers. Con\u00e7ues pour g\u00e9rer de grands volumes de production, nos machines garantissent des cr\u00eapes parfaites, adapt\u00e9es \u00e0 tout type de recette, qu'elle soit sucr\u00e9e ou sal\u00e9e. Qu'il s'agisse de farines simples ou compl\u00e8tes, nos machines s'adaptent facilement aux diff\u00e9rents ingr\u00e9dients, offrant une polyvalence qui les rend id\u00e9ales pour r\u00e9pondre \u00e0 toutes les exigences de production.","link":"https:\/\/italyfoodequipment.com\/fr\/categorie-produit\/machines-a-pates\/machines-electriques\/crepes-et-piadine\/","name":"Crepes et Piadine","slug":"crepes-et-piadine","taxonomy":"product_cat","parent":2402,"meta":[],"menu_order":7,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crepes et Piadine - Italy Food Equipment - machine \u00e0 cr\u00eapes professionnelle<\/title>\n<meta name=\"description\" content=\"Machines automatiques pour la production de cr\u00eapes rondes et rectanguli\u00e8res qui Vous permettentd&#039;utiliser plusieurs ingr\u00e9dients: douces, sal\u00e9es, avec des farines integrales, etc.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/italyfoodequipment.com\/fr\/categorie-produit\/machines-a-pates\/machines-electriques\/crepes-et-piadine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crepes et Piadine - Italy Food Equipment - machine \u00e0 cr\u00eapes professionnelle\" \/>\n<meta property=\"og:description\" content=\"Machines automatiques pour la production de cr\u00eapes rondes et rectanguli\u00e8res qui Vous permettentd&#039;utiliser plusieurs ingr\u00e9dients: douces, sal\u00e9es, avec des farines integrales, etc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/italyfoodequipment.com\/fr\/categorie-produit\/machines-a-pates\/machines-electriques\/crepes-et-piadine\/\" \/>\n<meta property=\"og:site_name\" content=\"Italy Food Equipment\" \/>\n<meta property=\"og:image\" content=\"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2021\/04\/IFELOGO2021.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"239\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ItalyFoodEquipm\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/categorie-produit\\\/machines-a-pates\\\/machines-electriques\\\/crepes-et-piadine\\\/\",\"url\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/categorie-produit\\\/machines-a-pates\\\/machines-electriques\\\/crepes-et-piadine\\\/\",\"name\":\"Crepes et Piadine - Italy Food Equipment - machine \u00e0 cr\u00eapes professionnelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/#website\"},\"description\":\"Machines automatiques pour la production de cr\u00eapes rondes et rectanguli\u00e8res qui Vous permettentd'utiliser plusieurs ingr\u00e9dients: douces, sal\u00e9es, avec des farines integrales, etc.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/categorie-produit\\\/machines-a-pates\\\/machines-electriques\\\/crepes-et-piadine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/categorie-produit\\\/machines-a-pates\\\/machines-electriques\\\/crepes-et-piadine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Machines \u00e0 P\u00e2tes\",\"item\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/categorie-produit\\\/machines-a-pates\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Machines \u00e9lectriques\",\"item\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/categorie-produit\\\/machines-a-pates\\\/machines-electriques\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Crepes et Piadine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/\",\"name\":\"Italy Food Equipment\",\"description\":\"\u00c9quipement professionel fabriqu\u00e9 en Italie. Machines \u00e0 p\u00e2tes fra\u00eeches, petrins, fours et accessoires pour pizzerias et restaurants. Conseils professionnels.\",\"publisher\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/#organization\",\"name\":\"Italy Food Equipment\",\"url\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IFELOGO2021.png\",\"contentUrl\":\"https:\\\/\\\/www.italyfoodequipment.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IFELOGO2021.png\",\"width\":800,\"height\":239,\"caption\":\"Italy Food Equipment\"},\"image\":{\"@id\":\"https:\\\/\\\/italyfoodequipment.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/italyfoodequipment1\\\/\",\"https:\\\/\\\/x.com\\\/ItalyFoodEquipm\",\"https:\\\/\\\/www.instagram.com\\\/italyfoodequipment\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/italyfoodequipment\\\/pins\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCei5o9afXohrZxw6DvkF88Q\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crepes et Piadine - Italy Food Equipment - machine \u00e0 cr\u00eapes professionnelle","description":"Machines automatiques pour la production de cr\u00eapes rondes et rectanguli\u00e8res qui Vous permettentd'utiliser plusieurs ingr\u00e9dients: douces, sal\u00e9es, avec des farines integrales, etc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/italyfoodequipment.com\/fr\/categorie-produit\/machines-a-pates\/machines-electriques\/crepes-et-piadine\/","og_locale":"fr_FR","og_type":"article","og_title":"Crepes et Piadine - Italy Food Equipment - machine \u00e0 cr\u00eapes professionnelle","og_description":"Machines automatiques pour la production de cr\u00eapes rondes et rectanguli\u00e8res qui Vous permettentd'utiliser plusieurs ingr\u00e9dients: douces, sal\u00e9es, avec des farines integrales, etc.","og_url":"https:\/\/italyfoodequipment.com\/fr\/categorie-produit\/machines-a-pates\/machines-electriques\/crepes-et-piadine\/","og_site_name":"Italy Food Equipment","og_image":[{"width":800,"height":239,"url":"https:\/\/italyfoodequipment.com\/wp-content\/uploads\/2021\/04\/IFELOGO2021.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ItalyFoodEquipm","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/italyfoodequipment.com\/fr\/categorie-produit\/machines-a-pates\/machines-electriques\/crepes-et-piadine\/","url":"https:\/\/italyfoodequipment.com\/fr\/categorie-produit\/machines-a-pates\/machines-electriques\/crepes-et-piadine\/","name":"Crepes et Piadine - Italy Food Equipment - machine \u00e0 cr\u00eapes professionnelle","isPartOf":{"@id":"https:\/\/italyfoodequipment.com\/fr\/#website"},"description":"Machines automatiques pour la production de cr\u00eapes rondes et rectanguli\u00e8res qui Vous permettentd'utiliser plusieurs ingr\u00e9dients: douces, sal\u00e9es, avec des farines integrales, etc.","breadcrumb":{"@id":"https:\/\/italyfoodequipment.com\/fr\/categorie-produit\/machines-a-pates\/machines-electriques\/crepes-et-piadine\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/italyfoodequipment.com\/fr\/categorie-produit\/machines-a-pates\/machines-electriques\/crepes-et-piadine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/italyfoodequipment.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Machines \u00e0 P\u00e2tes","item":"https:\/\/italyfoodequipment.com\/fr\/categorie-produit\/machines-a-pates\/"},{"@type":"ListItem","position":3,"name":"Machines \u00e9lectriques","item":"https:\/\/italyfoodequipment.com\/fr\/categorie-produit\/machines-a-pates\/machines-electriques\/"},{"@type":"ListItem","position":4,"name":"Crepes et Piadine"}]},{"@type":"WebSite","@id":"https:\/\/italyfoodequipment.com\/fr\/#website","url":"https:\/\/italyfoodequipment.com\/fr\/","name":"Italy Food Equipment","description":"\u00c9quipement professionel fabriqu\u00e9 en Italie. Machines \u00e0 p\u00e2tes fra\u00eeches, petrins, fours et accessoires pour pizzerias et restaurants. Conseils professionnels.","publisher":{"@id":"https:\/\/italyfoodequipment.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/italyfoodequipment.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/italyfoodequipment.com\/fr\/#organization","name":"Italy Food Equipment","url":"https:\/\/italyfoodequipment.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/italyfoodequipment.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.italyfoodequipment.com\/wp-content\/uploads\/2021\/04\/IFELOGO2021.png","contentUrl":"https:\/\/www.italyfoodequipment.com\/wp-content\/uploads\/2021\/04\/IFELOGO2021.png","width":800,"height":239,"caption":"Italy Food Equipment"},"image":{"@id":"https:\/\/italyfoodequipment.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/italyfoodequipment1\/","https:\/\/x.com\/ItalyFoodEquipm","https:\/\/www.instagram.com\/italyfoodequipment\/","https:\/\/www.pinterest.com\/italyfoodequipment\/pins\/","https:\/\/www.youtube.com\/channel\/UCei5o9afXohrZxw6DvkF88Q"]}]}},"_links":{"self":[{"href":"https:\/\/italyfoodequipment.com\/fr\/wp-json\/wp\/v2\/product_cat\/2717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/italyfoodequipment.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/italyfoodequipment.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/italyfoodequipment.com\/fr\/wp-json\/wp\/v2\/product_cat\/2402"}],"wp:post_type":[{"href":"https:\/\/italyfoodequipment.com\/fr\/wp-json\/wp\/v2\/product?product_cat=2717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}